{"id":4885,"date":"2020-10-12T13:59:47","date_gmt":"2020-10-12T11:59:47","guid":{"rendered":"https:\/\/cordoba.salesianos.edu\/colegio\/?page_id=4885"},"modified":"2026-03-01T10:36:10","modified_gmt":"2026-03-01T09:36:10","slug":"admisiones","status":"publish","type":"page","link":"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/","title":{"rendered":"Admisiones"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; transparent_background=\u00bboff\u00bb make_fullwidth=\u00bboff\u00bb use_custom_width=\u00bboff\u00bb width_unit=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title_font_color=\u00bb#ffffff\u00bb button_one_text_tablet=\u00bb\u00bb button_one_text_phone=\u00bb\u00bb button_one_text_last_edited=\u00bbon|desktop\u00bb module_class=\u00bbpagina-imagen-cabecera\u00bb _builder_version=\u00bb4.23.1&#8243; title_font_size=\u00bb40px\u00bb background_image=\u00bbhttps:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/02\/Cordoba-MMQE-2024_banner-web-scaled.jpg\u00bb background_layout=\u00bblight\u00bb custom_padding=\u00bb350px||0px||false|false\u00bb background_last_edited=\u00bbon|desktop\u00bb background_image_phone=\u00bbhttps:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/02\/Cordoba-MMQE-2024_banner-web-scaled.jpg\u00bb background_enable_image_phone=\u00bbon\u00bb parallax_phone=\u00bboff\u00bb background_url=\u00bbhttps:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/05\/fondobosco-1.jpg\u00bb button_one_letter_spacing_hover=\u00bb0&#8243; button_two_letter_spacing_hover=\u00bb0&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb button_one_text__hover_enabled=\u00bboff|desktop\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bbrgba(255,255,255,0.83)\u00bb background_enable_image=\u00bboff\u00bb background_blend=\u00bbsoft-light\u00bb module_alignment=\u00bbcenter\u00bb min_height=\u00bb7355.2px\u00bb custom_margin=\u00bb-1px|||||\u00bb custom_padding=\u00bb0px|0px|70px|0px||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; text_font=\u00bb|300|||||||\u00bb text_font_size=\u00bb34px\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbLato|300|||||||\u00bb header_2_font_size=\u00bb49px\u00bb text_orientation=\u00bbcenter\u00bb custom_margin=\u00bb1px||1px\u00bb custom_padding=\u00bb0px||0px|||\u00bb text_text_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"color: #dc001b; font-size: 45px;\">Escolarizaci\u00f3n 2026-2027<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.16&#8243; text_font_size=\u00bb18px\u00bb text_text_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">INFANTIL, PRIMARIA, ESO Y BACHILLERATO<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bb#calendario\u00bb button_text=\u00bbCalendario de Escolarizaci\u00f3n\u00bb button_alignment=\u00bbcenter\u00bb admin_label=\u00bbcalendario\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_cta title=\u00bbHay un sitio para ti\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbCabin Sketch|700|on||||||\u00bb header_font_size=\u00bb40&#8243; header_letter_spacing=\u00bb6px\u00bb header_line_height=\u00bb1.5em\u00bb use_background_color=\u00bboff\u00bb background_layout=\u00bblight\u00bb custom_padding=\u00bb0px||1px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_cta][et_pb_divider divider_style=\u00bbdashed\u00bb _builder_version=\u00bb4.16&#8243; height=\u00bb0px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb|||\u00bb custom_padding=\u00bb0px|||\u00bb custom_padding_tablet=\u00bb||0px|\u00bb custom_padding_phone=\u00bb||0px|\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; text_font_size=\u00bb18px\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong style=\"font-size: 18px;\"><em>La Consejer\u00eda de Educaci\u00f3n y Deporte convoca el procedimiento de admisi\u00f3n del alumnado en los centros docentes p\u00fablicos y privados concertados para cursar las ense\u00f1anzas de segundo ciclo de educaci\u00f3n infantil, educaci\u00f3n primaria, educaci\u00f3n especial, educaci\u00f3n secundaria obligatoria y bachillerato para el curso escolar 2026\/27.\u00a0<\/em><\/strong><\/p>\n<p>Durante todo el mes de marzo permanecer\u00e1 abierto en Andaluc\u00eda el plazo para la presentaci\u00f3n de solicitudes de admisi\u00f3n correspondientes al pr\u00f3ximo curso escolar. Se inicia de este modo el proceso de escolarizaci\u00f3n en el que participan todos los ni\u00f1os y ni\u00f1as que se incorporan por primera vez al sistema educativo, tanto en centros p\u00fablicos como privados concertados, as\u00ed como el alumnado que cambie de centro escolar.<\/p>\n<p><span style=\"font-size: 18px;\">El plazo de solicitud para el <\/span><strong style=\"font-size: 18px;\">resto de las etapas (Ciclos Formativos) <\/strong><span style=\"font-size: 18px;\">tienen plazos de escolarizaci\u00f3n distintos, cuyas fechas se dar\u00e1n a conocer en cuanto las publique la administraci\u00f3n educativa.<\/span><\/p>\n<p>El<strong> Colegio Salesiano de C\u00f3rdoba<\/strong> es un centro<strong> concertado en todas sus etapas<\/strong>, y dispone de<strong> tres l\u00edneas<\/strong> en las etapas de<strong> Infantil, Primaria y E.S.O<\/strong>.;<strong> dos l\u00edneas <\/strong>en la etapa de<strong> Bachillerato y una l\u00ednea en la etapa de Ciclos Formativos. <\/strong><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/cordoba.salesianos.edu\/colegio\/oferta-educativa\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbConoce nuestra oferta educativa\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_icon=\u00bb&#xe086;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb button_text_color_hover=\u00bb#ffffff\u00bb button_bg_color_hover=\u00bb#cc1c1c\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_text_size__hover=\u00bbnull\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover=\u00bbnull\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover=\u00bbnull\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover=\u00bbnull\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover=\u00bbnull\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_border_width__hover=\u00bbnull\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover=\u00bbnull\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover=\u00bbnull\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_border_color__hover=\u00bbnull\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover=\u00bbnull\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover=\u00bbnull\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_border_radius__hover=\u00bbnull\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover=\u00bbnull\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover=\u00bbnull\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover=\u00bbnull\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover=\u00bbnull\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover=\u00bbnull\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#cc1c1c\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover=\u00bbnull\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover=\u00bbnull\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||25px\u00bb custom_padding_tablet=\u00bb|||0px\u00bb custom_padding_phone=\u00bb|||0px\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbADMISI\u00d3N SOLICITUDES | 1 marzo-31 marzo\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><em>Las solicitudes pueden presentarse de distintos modos:<br \/> <\/em><\/p>\n<p><a href=\"tel:\/\/952251541\"><\/a><strong style=\"font-size: 16px;\">PRESENTACI\u00d3N TELEM\u00c1TICA | <\/strong><span style=\"font-size: 16px;\">\u00a0La presentaci\u00f3n telem\u00e1tica puede hacerse de distintos modos: mediante certificado digital o firma electr\u00f3nica, mediante identificaci\u00f3n a trav\u00e9s del sistema Cl@ve o mediante una clave iAnde, que podr\u00e1 obtener registr\u00e1ndose en la Secretar\u00eda Virtual de la Consejer\u00eda de Educaci\u00f3n y Deporte, para lo que necesitar\u00e1 su DNI y n\u00famero de m\u00f3vil. Tambi\u00e9n es posible cumplimentar un formulario online, que posteriormente deber\u00e1 llevar posteriormente al centro elegido.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_button button_url=\u00bbhttps:\/\/www.juntadeandalucia.es\/educacion\/secretariavirtual\/solicitudes\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbSolicitud | Presentaci\u00f3n telem\u00e1tica\u00bb button_alignment=\u00bbcenter\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.20.0&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_icon=\u00bb&#xe058;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_text_size__hover=\u00bbnull\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover=\u00bbnull\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover=\u00bbnull\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover=\u00bbnull\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover=\u00bbnull\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_border_width__hover=\u00bbnull\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover=\u00bbnull\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover=\u00bbnull\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_border_color__hover=\u00bbnull\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover=\u00bbnull\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover=\u00bbnull\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_border_radius__hover=\u00bbnull\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover=\u00bbnull\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover=\u00bbnull\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover=\u00bbnull\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover=\u00bbnull\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover=\u00bbnull\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#cc1c1c\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover=\u00bbnull\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover=\u00bbnull\u00bb][\/et_pb_button][et_pb_blurb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong style=\"font-size: 16px;\">EN SECRETAR\u00cdA<\/strong><span style=\"font-size: 16px;\"> | Las personas que lo prefieran podr\u00e1n presentar la solicitud de manera presencial.\u00a0<\/span><\/p>\n<p><strong>HORARIO DE ATENCI\u00d3N | <\/strong>Lunes, Martes, Mi\u00e9rcoles, Jueves y Viernes, de 9 a 11 h. \/ Martes de 17:30 a 19:30.<strong><br \/><\/strong><\/p>\n<p><strong>EMAIL<\/strong> | <a href=\"mailto:secretaria.cordoba@salesianos.edu\">secretaria.cordoba@salesianos.edu<\/a><\/p>\n<p><strong>TEL\u00c9FONO | <\/strong><a href=\"tel:\/\/952251541\">957 48 20 00<\/a><span style=\"font-size: 16px;\">\u00a0<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_button button_url=\u00bbhttps:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2024\/02\/3_Anexo-III_002535_5-1.pdf\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbImpreso | Solicitud de admisi\u00f3n\u00bb button_alignment=\u00bbcenter\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.23.1&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_icon=\u00bb&#xe058;||divi||400&#8243; button_icon_placement=\u00bbleft\u00bb button_on_hover=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_text_size__hover=\u00bbnull\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover=\u00bbnull\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover=\u00bbnull\u00bb button_text_color__hover_enabled=\u00bbon\u00bb button_text_color__hover=\u00bb#ffffff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover=\u00bbnull\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover=\u00bbnull\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_border_width__hover=\u00bbnull\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover=\u00bbnull\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover=\u00bbnull\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_border_color__hover=\u00bbnull\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover=\u00bbnull\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover=\u00bbnull\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_border_radius__hover=\u00bbnull\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover=\u00bbnull\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover=\u00bbnull\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover=\u00bbnull\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover=\u00bbnull\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover=\u00bbnull\u00bb button_bg_color__hover_enabled=\u00bbon\u00bb button_bg_color__hover=\u00bb#cc1c1c\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover=\u00bbnull\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover=\u00bbnull\u00bb][\/et_pb_button][et_pb_text disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<strong><em>Una vez cumplimentada la solicitud hacer FOTOCOPIA DE TODAS LAS P\u00c1GINAS y entregar ORIGINAL Y FOTOCOPIA EN SECRETAR\u00cdA<\/em><\/strong><br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.16&#8243; min_height=\u00bb717.9px\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb0px||2px|||\u00bb custom_padding_tablet=\u00bb||0px|\u00bb custom_padding_phone=\u00bb||0px|\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|300|||||||\u00bb header_2_font_size=\u00bb30px\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb||2px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Plazas ofertadas para el curso escolar 2026-2027<\/h2>\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.23.1&#8243; text_font_size=\u00bb18px\u00bb header_text_align=\u00bbcenter\u00bb header_2_font=\u00bb|300|||||||\u00bb header_2_font_size=\u00bb30px\u00bb custom_margin=\u00bb|-5px|10px|||\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: justify;\">Este a\u00f1o, nuestra oferta de plazas vacantes es:<\/p>\n<table style=\"border-color: #575753; margin-left: auto; margin-right: auto; height: 414px;\" width=\"806\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; text-align: center; width: 469.5px; height: 23px;\"><strong>NIVEL EDUCATIVO<\/strong><\/td>\n<td style=\"border-color: #45453e; text-align: center; width: 320.5px; height: 23px;\"><strong>PLAZAS OFERTADAS*<\/strong><\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td style=\"border-color: #45453e; width: 469.5px; height: 23px;\">Infantil 3 a\u00f1os<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; height: 23px;\">66<\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td style=\"border-color: #45453e; width: 469.5px; height: 23px;\">Infantil 4 a\u00f1os<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; height: 23px;\">0*<\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td style=\"border-color: #45453e; width: 469.5px; height: 23px;\">Infantil 5 a\u00f1os<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; height: 23px;\">4<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; width: 469.5px; text-align: center; height: 23px;\">1\u00ba Primaria<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; text-align: center; height: 23px;\">0*<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; width: 469.5px; text-align: center; height: 23px;\">2\u00ba Primaria<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; text-align: center; height: 23px;\">0*<\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td style=\"border-color: #45453e; width: 469.5px; height: 23px;\">3\u00ba Primaria<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; height: 23px;\">8<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; width: 469.5px; text-align: center; height: 23px;\">4\u00ba Primaria<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; text-align: center; height: 23px;\">0*<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; width: 469.5px; text-align: center; height: 23px;\">5\u00ba Primaria<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; text-align: center; height: 23px;\">0*<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; width: 469.5px; text-align: center; height: 23px;\">6\u00ba Primaria<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; text-align: center; height: 23px;\">0*<\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td style=\"border-color: #45453e; width: 469.5px; height: 23px;\">1\u00ba ESO<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; height: 23px;\">8<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; width: 469.5px; text-align: center; height: 23px;\">2\u00ba ESO<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; height: 23px; text-align: center;\">0<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; width: 469.5px; height: 23px; text-align: center;\">3\u00ba ESO<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; height: 23px; text-align: center;\">1<\/td>\n<\/tr>\n<tr style=\"text-align: center;\">\n<td style=\"border-color: #45453e; width: 469.5px; height: 23px;\">4\u00ba ESO<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; height: 23px;\">4<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; width: 469.5px; text-align: center; height: 23px;\">1\u00ba Bachillerato de Ciencias**<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; text-align: center; height: 23px;\">35<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; width: 469.5px; text-align: center; height: 23px;\">1\u00ba Bachillerato Humanidades y Ciencias Sociales**<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; text-align: center; height: 23px;\">35<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; width: 469.5px; text-align: center; height: 23px;\">2\u00ba Bachillerato de Ciencias**<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; text-align: center; height: 23px;\">14<\/td>\n<\/tr>\n<tr style=\"height: 23px;\">\n<td style=\"border-color: #45453e; width: 469.5px; text-align: center; height: 23px;\">2\u00ba Bachillerato Humanidades y Ciencias Sociales**<\/td>\n<td style=\"border-color: #45453e; width: 320.5px; text-align: center; height: 23px;\">16<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb|82px||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><em><strong>*<\/strong>Aunque en algunos cursos no se oferten plazas, es posible presentar la solicitud a la espera de que se produzca alguna vacante adicional. La presentaci\u00f3n de solicitud es condici\u00f3n indispensable para optar a una vacante.<\/em><\/p>\n<p><strong>**<\/strong><i>La etapa de bachillerato es privada, no est\u00e1 concertada.<\/i><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||25px\u00bb custom_padding_tablet=\u00bb|||0px\u00bb custom_padding_phone=\u00bb|||0px\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_padding=\u00bb|||0px||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><span style=\"font-size: large;\">DOCUMENTACI\u00d3N DE INTER\u00c9S<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: large;\">Para acceder al documento clica sobre el nombre del documento:<\/span><\/p>\n<blockquote>\n<p><span style=\"font-size: large;\">1.-\u00a0<a href=\"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/Solicitud-Anexo-III.pdf\">Solicitud Anexo III<\/a><\/span><br \/><span style=\"font-size: large;\">2.- <a href=\"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/Oferta-Educativa.pdf\">Oferta educativa<\/a><\/span><br \/><span style=\"font-size: large;\">3.-\u00a0<a href=\"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/Calendario_26-27.pdf\">Calendario<\/a><\/span><br \/><span style=\"font-size: large;\">4.- <a href=\"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/Cuadro-informativo_criterios-baremacion-26-27_articulos.pdf\">Cuadro informativo \u2013 Criterios de baremaci\u00f3n<\/a><\/span><br \/><span style=\"font-size: large;\">5.- <a href=\"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/Mapa-y-callejero-viales-Infantil-Primaria.pdf\">Mapa y callejero viales Infantil Primaria<\/a><\/span><br \/><span style=\"font-size: large;\">6.- <a href=\"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/Mapa-y-callejero-ESO.pdf\">Mapa y callejero viales Infantil ESO<\/a><\/span><br \/><span style=\"font-size: large;\">7.- <a href=\"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/Aclaraciones-a-las-relaciones-de-calles-26_27.pdf\">Aclaraciones a las relaciones de calles<\/a><\/span><br \/><span style=\"font-size: large;\">8.- <a href=\"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/Nota-informativa_NO-amplicacion-de-ratio_26-27.pdf\">Nota informativa sobre la no ampliaci\u00f3n de la ratio<\/a><\/span><\/p>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_padding=\u00bb|||0px||\u00bb link_option_url=\u00bbhttps:\/\/cordoba.salesianos.edu\/wp-content\/uploads\/2025\/01\/Dossier-Bachillerato_2025_2026_B1_Alumnos-Nuevos.pdf\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<blockquote>\n<p><span style=\"font-size: large;\">\u00a0**<\/span><span style=\"font-size: large;\">\u00a0<a href=\"https:\/\/cordoba.salesianos.edu\/wp-content\/uploads\/2025\/01\/Dossier-Bachillerato_2025_2026_B1_Alumnos-Nuevos.pdf\">Dossier Bachillerato<\/a><\/span><\/p>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_divider _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb71px\u00bb custom_padding=\u00bb||14px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; text_font_size=\u00bb18px\u00bb header_2_font=\u00bb|300|||||||\u00bb header_2_font_size=\u00bb30px\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Fechas importantes en el proceso de escolarizaci\u00f3n<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbcalendario\u00bb module_id=\u00bbcalendario\u00bb module_class=\u00bbcalendario\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||9px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbPRESENTACI\u00d3N DE SOLICITUDES | 1 de MARZO\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Del 1 de marzo al 31 de marzo.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbLISTA BAREMADA | 20 de abril\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"font-size: 16px;\">Los centros har\u00e1n p\u00fablica en su tabl\u00f3n de anuncios, antes del 20 de abril, la relaci\u00f3n de solicitantes con la puntuaci\u00f3n asignada y, a partir de esa fecha, se abrir\u00e1 un plazo de 10 d\u00edas lectivos para la presentaci\u00f3n de alegaciones.<\/span><\/p>\n<p><span style=\"font-size: 16px;\"><span>Del 21 de abril al 4 de mayo comienza el tr\u00e1mite de audiencia establecido en el art\u00edculo 23.1.<\/span><\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbSORTEO EN CASO DE EMPATES | 13 de mayo\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Si tras la aplicaci\u00f3n de los criterios de baremaci\u00f3n, se producen empates, se aplicar\u00e1 el resultado del sorteo p\u00fablico.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbLISTA DE ADMITIDOS | 14 de mayo\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Se publicar\u00e1 la relaci\u00f3n definitiva de admitidos en los centros elegidos como prioritarios.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbREUBICACI\u00d3N NO ADMITIDOS| 25 de mayo\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Publicaci\u00f3n de la Resoluci\u00f3n de adjudicaci\u00f3n de plaza del alumnado no admitido en el centro docente elegido como prioritario (reubicaci\u00f3n).<\/p>\n<p><span>El 26 de mayo de 2025 comenzar\u00e1 el plazo establecido para la presentaci\u00f3n de recursos de alzada y reclamaciones ante la persona titular de la Consejer\u00eda competente en materia de educaci\u00f3n establecido en el art\u00edculo 48 del Decreto 21\/2020, de 17 de febrero.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbMATRICULACIONES | Del 1 al 8 de junio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Plazo de matriculaci\u00f3n del alumnado en 2\u00ba ciclo de educaci\u00f3n infantil, educaci\u00f3n primaria y educaci\u00f3n especial.\u00a0<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bbMATRICULACIONES | Del 1 al 10 de julio\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe023;||divi||400&#8243; icon_color=\u00bb#e02b20&#8243; icon_placement=\u00bbleft\u00bb content_max_width=\u00bb881px\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_text_color=\u00bb#E02B20&#8243; header_font_size=\u00bb20px\u00bb body_font_size=\u00bb16px\u00bb body_line_height=\u00bb1.3em\u00bb custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Plazo de matriculaci\u00f3n del alumnado en educaci\u00f3n secundaria obligatoria y bachillerato.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb12px||11px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.4&#8243; custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Para acceder a la informaci\u00f3n detallada sobre el proceso de admisi\u00f3n, normativa, criterios de admisi\u00f3n, \u00e1reas de influencia, preguntas frecuentes, etc. le recomendamos consultar la <a href=\"https:\/\/www.juntadeandalucia.es\/educacion\/portales\/es\/web\/escolarizacion\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>p\u00e1gina web de escolarizaci\u00f3n de la Consejer\u00eda de Educaci\u00f3n y Deporte de la Junta de Andaluc\u00eda<\/strong><\/a>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb30px|40px|30px|40px\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb box_shadow_style=\u00bbpreset3&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_contact_form email=\u00bbsecretaria.cordoba@salesianos.edu\u00bb title=\u00bb\u00bfAlguna duda sobre el procedimiento de admisi\u00f3n? Te ayudamos.\u00bb custom_message=\u00bb%%name%% ha enviado un mensaje solicitando informaci\u00f3n sobre PROCEDIMIENTO DE ADMISI\u00d3N CURSO 2022-23 (https:\/\/cordoba.salesianos.edu\/colegio\/admisiones):||et_pb_line_break_holder||||et_pb_line_break_holder||&#8212;&#8212;||et_pb_line_break_holder||%%message%%||et_pb_line_break_holder||&#8212;&#8212;||et_pb_line_break_holder||||et_pb_line_break_holder||Puedes responder a este correo directamente salvo que te lo hayan REENVIADO. En ese caso, tendr\u00e1s que redactar un NUEVO CORREO con la respuesta y enviarlo a %%email%%.||et_pb_line_break_holder||||et_pb_line_break_holder||Para cualquier problema o sugerencia sobre el sistema de formularios de la web envia un correo a secretaria.cordoba@salesianos.edu.\u00bb success_message=\u00bbGracias por interesarte en nuestro centro. Nos pondremos en contacto contigo lo antes posible.\u00bb module_id=\u00bbet_pb_contact_form_0&#8243; _builder_version=\u00bb4.16&#8243; _unique_id=\u00bb4e185a7d-6ebd-45e3-980a-350ed39186a4&#8243; title_level=\u00bbh2&#8243; title_font=\u00bbLato|300|||||||\u00bb title_font_size=\u00bb30px\u00bb title_line_height=\u00bb1.2em\u00bb custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bb#e02b20&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_contact_field field_id=\u00bbName\u00bb field_title=\u00bbNombre\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbEmail\u00bb field_title=\u00bbDirecci\u00f3n de correo electr\u00f3nico\u00bb field_type=\u00bbemail\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbMessage\u00bb field_title=\u00bbMensaje\u00bb field_type=\u00bbtext\u00bb fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][et_pb_contact_field field_id=\u00bbPrivacidad\u00bb field_title=\u00bb \u00bb field_type=\u00bbcheckbox\u00bb checkbox_options=\u00bb%91{%22value%22:%22 Acepto la pol\u00edtica de privacidad del sitio.%22,%22checked%22:0,%22dragID%22:0}%93&#8243; fullwidth_field=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb27px|0px|12.6px|0px||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; text_font=\u00bb|300|||||||\u00bb text_font_size=\u00bb36px\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bbLato|300|||||||\u00bb header_2_font_size=\u00bb49px\u00bb header_3_font=\u00bb||||||||\u00bb text_orientation=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>\u00a1Gracias por interesarte en nuestro centro!<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.16&#8243; width=\u00bb21.7%\u00bb custom_padding=\u00bb||12px|20px||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb|2px||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><\/h1>\n<h1><\/h1>\n<h1><\/h1>\n<h1><\/h1>\n<h1 style=\"text-align: center;\">Admisi\u00f3n otras\u00a0 etapas:<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbCiclos Formativos\u00bb url=\u00bbhttps:\/\/cordoba.salesianos.edu\/colegio\/admisiones-ccff\/\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#x6b;||divi||400&#8243; image_icon_background_color=\u00bb#ffffff\u00bb image_icon_width=\u00bb48px\u00bb admin_label=\u00bbCiclos Formativos\u00bb _builder_version=\u00bb4.16&#8243; header_text_color=\u00bb#666666&#8243; image_icon_custom_padding=\u00bb25px|25px|25px|25px|false|false\u00bb text_orientation=\u00bbcenter\u00bb border_radii_image=\u00bbon|100%|100%|100%|100%\u00bb border_width_all_image=\u00bb3px\u00bb border_color_all_image=\u00bb#666666&#8243; use_circle=\u00bbon\u00bb use_circle_border=\u00bbon\u00bb circle_border_color=\u00bb#666666&#8243; circle_color=\u00bb#ffffff\u00bb global_colors_info=\u00bb{}\u00bb image_icon_background_color__sticky_enabled=\u00bb#dc001b\u00bb image_icon_background_color__sticky=\u00bb#dc001b\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escolarizaci\u00f3n 2026-2027INFANTIL, PRIMARIA, ESO Y BACHILLERATOLa Consejer\u00eda de Educaci\u00f3n y Deporte convoca el procedimiento de admisi\u00f3n del alumnado en los centros docentes p\u00fablicos y privados concertados para cursar las ense\u00f1anzas de segundo ciclo de educaci\u00f3n infantil, educaci\u00f3n primaria, educaci\u00f3n especial, educaci\u00f3n secundaria obligatoria y bachillerato para el curso escolar 2026\/27.\u00a0 Durante todo el mes de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8038,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-4885","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Admisiones - Colegio Salesiano San Francisco de Sales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Admisiones - Colegio Salesiano San Francisco de Sales\" \/>\n<meta property=\"og:description\" content=\"Escolarizaci\u00f3n 2026-2027INFANTIL, PRIMARIA, ESO Y BACHILLERATOLa Consejer\u00eda de Educaci\u00f3n y Deporte convoca el procedimiento de admisi\u00f3n del alumnado en los centros docentes p\u00fablicos y privados concertados para cursar las ense\u00f1anzas de segundo ciclo de educaci\u00f3n infantil, educaci\u00f3n primaria, educaci\u00f3n especial, educaci\u00f3n secundaria obligatoria y bachillerato para el curso escolar 2026\/27.\u00a0 Durante todo el mes de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano San Francisco de Sales\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-01T09:36:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/01\/CORD_MMQE-cartel_v2-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1810\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/admisiones\\\/\",\"url\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/admisiones\\\/\",\"name\":\"Admisiones - Colegio Salesiano San Francisco de Sales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/admisiones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/admisiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/CORD_MMQE-cartel_v2-1-scaled.jpg\",\"datePublished\":\"2020-10-12T11:59:47+00:00\",\"dateModified\":\"2026-03-01T09:36:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/admisiones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/admisiones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/admisiones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/CORD_MMQE-cartel_v2-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/CORD_MMQE-cartel_v2-1-scaled.jpg\",\"width\":1810,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/admisiones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Admisiones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano San Francisco de Sales\",\"description\":\"P\u00e1gina oficial Salesianos C\u00f3rdoba\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cordoba.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Admisiones - Colegio Salesiano San Francisco de Sales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/","og_locale":"es_ES","og_type":"article","og_title":"Admisiones - Colegio Salesiano San Francisco de Sales","og_description":"Escolarizaci\u00f3n 2026-2027INFANTIL, PRIMARIA, ESO Y BACHILLERATOLa Consejer\u00eda de Educaci\u00f3n y Deporte convoca el procedimiento de admisi\u00f3n del alumnado en los centros docentes p\u00fablicos y privados concertados para cursar las ense\u00f1anzas de segundo ciclo de educaci\u00f3n infantil, educaci\u00f3n primaria, educaci\u00f3n especial, educaci\u00f3n secundaria obligatoria y bachillerato para el curso escolar 2026\/27.\u00a0 Durante todo el mes de [&hellip;]","og_url":"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/","og_site_name":"Colegio Salesiano San Francisco de Sales","article_modified_time":"2026-03-01T09:36:10+00:00","og_image":[{"width":1810,"height":2560,"url":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/01\/CORD_MMQE-cartel_v2-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/","url":"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/","name":"Admisiones - Colegio Salesiano San Francisco de Sales","isPartOf":{"@id":"https:\/\/cordoba.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/#primaryimage"},"image":{"@id":"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/#primaryimage"},"thumbnailUrl":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/01\/CORD_MMQE-cartel_v2-1-scaled.jpg","datePublished":"2020-10-12T11:59:47+00:00","dateModified":"2026-03-01T09:36:10+00:00","breadcrumb":{"@id":"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/#primaryimage","url":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/01\/CORD_MMQE-cartel_v2-1-scaled.jpg","contentUrl":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2022\/01\/CORD_MMQE-cartel_v2-1-scaled.jpg","width":1810,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/cordoba.salesianos.edu\/colegio\/admisiones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cordoba.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Admisiones"}]},{"@type":"WebSite","@id":"https:\/\/cordoba.salesianos.edu\/colegio\/#website","url":"https:\/\/cordoba.salesianos.edu\/colegio\/","name":"Colegio Salesiano San Francisco de Sales","description":"P\u00e1gina oficial Salesianos C\u00f3rdoba","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cordoba.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/4885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=4885"}],"version-history":[{"count":57,"href":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/4885\/revisions"}],"predecessor-version":[{"id":9518,"href":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/4885\/revisions\/9518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/8038"}],"wp:attachment":[{"href":"https:\/\/cordoba.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=4885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}